{"id":943,"date":"2020-11-13T11:05:22","date_gmt":"2020-11-13T10:05:22","guid":{"rendered":"https:\/\/adixatex.com\/product\/rilevamento-e-spegnimento-di-scintille\/"},"modified":"2021-11-19T08:08:59","modified_gmt":"2021-11-19T07:08:59","slug":"rilevamento-e-spegnimento-di-scintille","status":"publish","type":"product","link":"https:\/\/www2.adixatex.com\/it\/prodotto\/rilevamento-e-spegnimento-di-scintille\/","title":{"rendered":"Rilevamento e spegnimento di scintille"},"content":{"rendered":"<div id=\"shortcode_container_tabs\" class=\"shortcode_container_tabs\"><div id=\"container_tabs_title\" class=\"container_tabs_title\"><\/div>\n<p class=\"container_tabs_title_mobile\">Dati tecnici<\/p><div class=\"container_tabs_content\">\n<div id=\"content_table\" class=\"content_table\">\n<table>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Contascintille<\/span><\/td>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">soglie regolabili da 1 a 999 scintille per unit\u00e0 di tempo<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Memoria del registro<\/span><\/td>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">fino a 2.500 eventi<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Connessione<\/span><\/td>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">fino a 4 rivelatori di scintille per linea<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Autonomia della batteria<\/span><\/td>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">4 ore<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Valutazione individuale e visualizzazione di ogni singolo rivelatore di scintille<\/span><\/td>\n<td style=\"text-align: left;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Uscite a rel\u00e8 programmabili<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Marcatura<\/span><\/td>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Disponibile con marcatura ATEX<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><span style=\"font-weight: 400;\">Certificato <\/span><\/td>\n<td style=\"text-align: left;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div id=\"content_table\" class=\"content_table\"><\/div>\n<\/div>\n<p class=\"container_tabs_title_mobile\">Accessori<\/p><div class=\"container_tabs_content\">\n<p>Sistema de Elevaci\u00f3n de Presi\u00f3n<\/p>\n<p>Unidad de auto-limpieza<\/p>\n<\/div>\n<p class=\"container_tabs_title_mobile\">Download materiale<\/p><div class=\"container_tabs_content\">\n<p><a href=\"https:\/\/adixatex.com\/wp-content\/uploads\/2020\/11\/TyB_Spark-extinguishing-systems.pdf\">Scheda tecnica (PDF)<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il sistema di Rilevamento e spegnimento di scintille del marchio tedesco T&amp;B electronic monitora le eventuali scintille tramite rilevatori ottici e lo comunica a un pannello di controllo che protegge le apparecchiature e i condotti degli impianti industriali attivando speciali sistemi di spegnimento ad acqua, provocando un rapido raffreddamento delle particelle.<\/p>\n","protected":false},"featured_media":13016,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[127],"product_tag":[],"class_list":{"0":"post-943","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prevenzione","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rilevamento e spegnimento di scintille - Adixatex<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rilevamento e spegnimento di scintille - Adixatex\" \/>\n<meta property=\"og:description\" content=\"Il sistema di Rilevamento e spegnimento di scintille del marchio tedesco T&amp;B electronic monitora le eventuali scintille tramite rilevatori ottici e lo comunica a un pannello di controllo che protegge le apparecchiature e i condotti degli impianti industriali attivando speciali sistemi di spegnimento ad acqua, provocando un rapido raffreddamento delle particelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/\" \/>\n<meta property=\"og:site_name\" content=\"Adixatex\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-19T07:08:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"847\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@adixprotection\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/\",\"url\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/\",\"name\":\"Rilevamento e spegnimento di scintille - Adixatex\",\"isPartOf\":{\"@id\":\"https:\/\/www2.adixatex.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png\",\"datePublished\":\"2020-11-13T10:05:22+00:00\",\"dateModified\":\"2021-11-19T07:08:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage\",\"url\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png\",\"contentUrl\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png\",\"width\":1200,\"height\":847,\"caption\":\"Instalaci\u00f3n Deteccion chispas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www2.adixatex.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/www2.adixatex.com\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rilevamento e spegnimento di scintille\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www2.adixatex.com\/#website\",\"url\":\"https:\/\/www2.adixatex.com\/\",\"name\":\"Adixatex\",\"description\":\"Prevenci\u00f3n y protecci\u00f3n de atm\u00f3sferas explosivas\",\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rilevamento e spegnimento di scintille - Adixatex","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Rilevamento e spegnimento di scintille - Adixatex","og_description":"Il sistema di Rilevamento e spegnimento di scintille del marchio tedesco T&amp;B electronic monitora le eventuali scintille tramite rilevatori ottici e lo comunica a un pannello di controllo che protegge le apparecchiature e i condotti degli impianti industriali attivando speciali sistemi di spegnimento ad acqua, provocando un rapido raffreddamento delle particelle.","og_url":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/","og_site_name":"Adixatex","article_modified_time":"2021-11-19T07:08:59+00:00","og_image":[{"width":1200,"height":847,"url":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@adixprotection","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/","url":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/","name":"Rilevamento e spegnimento di scintille - Adixatex","isPartOf":{"@id":"https:\/\/www2.adixatex.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage"},"image":{"@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage"},"thumbnailUrl":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png","datePublished":"2020-11-13T10:05:22+00:00","dateModified":"2021-11-19T07:08:59+00:00","breadcrumb":{"@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#primaryimage","url":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png","contentUrl":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2020\/10\/Instalacion-Deteccion-chispas-2.png","width":1200,"height":847,"caption":"Instalaci\u00f3n Deteccion chispas"},{"@type":"BreadcrumbList","@id":"https:\/\/www2.adixatex.com\/prodotto\/deteccion-y-apagado-de-chispas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www2.adixatex.com\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www2.adixatex.com\/productos\/"},{"@type":"ListItem","position":3,"name":"Rilevamento e spegnimento di scintille"}]},{"@type":"WebSite","@id":"https:\/\/www2.adixatex.com\/#website","url":"https:\/\/www2.adixatex.com\/","name":"Adixatex","description":"Prevenci\u00f3n y protecci\u00f3n de atm\u00f3sferas explosivas","inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product\/943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":1,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product\/943\/revisions"}],"predecessor-version":[{"id":944,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product\/943\/revisions\/944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/media\/13016"}],"wp:attachment":[{"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/media?parent=943"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product_brand?post=943"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product_cat?post=943"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www2.adixatex.com\/it\/wp-json\/wp\/v2\/product_tag?post=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}