{"id":2870,"date":"2021-02-22T10:23:20","date_gmt":"2021-02-22T09:23:20","guid":{"rendered":"https:\/\/adixatex.com\/servicios\/"},"modified":"2021-11-18T13:46:03","modified_gmt":"2021-11-18T12:46:03","slug":"servicos","status":"publish","type":"page","link":"https:\/\/www2.adixatex.com\/pt-pt\/servicos\/","title":{"rendered":"Servi\u00e7os"},"content":{"rendered":"<section class=\"shortcode_articles reverse_rows\">\n<article>\n<figure><img decoding=\"async\" src=\"https:\/\/adixatex.com\/wp-content\/uploads\/2021\/02\/2.-apoyo-tecnico.jpg\" alt=\"Apoio T\u00e9cnico\"\/><\/figure>\n<div class=\"info\"><span class=\"tag\">Apoio T\u00e9cnico<\/span>\n<h3>Apoio T\u00e9cnico<\/h3>\n\n<p>Faremos sempre o nosso melhor para resolver quaisquer problemas pelo telefone, e a nossa equipa de engenheiros est\u00e1 dispon\u00edvel para discutir quaisquer problemas com o seu equipamento para minimizar o tempo de inactividade.<\/p>\n<p>Adix oferece um servi\u00e7o e apoio inigual\u00e1veis aos nossos clientes em todo o mundo, assegurando que o seu equipamento funcione de forma \u00f3ptima 24 horas por dia, 7 dias por semana. Contacte-nos com pedidos de servi\u00e7o e apoio.<\/p>\n<p>A Adix tem uma equipa de t\u00e9cnicos de servi\u00e7o que pode ser enviada para o terreno para dar apoio \u00e0 instala\u00e7\u00e3o, comissionamento ou resolu\u00e7\u00e3o de problemas e repara\u00e7\u00e3o. A nossa equipa est\u00e1 totalmente certificada e treinada para opera\u00e7\u00f5es em \u00e1reas classificadas para p\u00f4r o seu equipamento a funcionar e reduzir o tempo de inactividade.<\/p>\n<\/div>\n<\/article>\n<article>\n<figure><img decoding=\"async\" src=\"https:\/\/adixatex.com\/wp-content\/uploads\/2021\/02\/3.-mantenimientos-y-reparaciones.jpg\" alt=\"Manuten\u00e7\u00e3o e repara\u00e7\u00f5es\"\/><\/figure>\n<div class=\"info\"><span class=\"tag\">Manuten\u00e7\u00e3o e repara\u00e7\u00f5es<\/span>\n<h3>Manuten\u00e7\u00e3o e repara\u00e7\u00f5es<\/h3>\n\n<p>A Adix pode fornecer um servi\u00e7o completo de repara\u00e7\u00e3o e remodela\u00e7\u00e3o de sistemas de preven\u00e7\u00e3o e protec\u00e7\u00e3o contra explos\u00f5es. Podemos trazer os sistemas de seguran\u00e7a de volta \u00e0s normas apropriadas e emitir um novo certificado de conformidade ATEX.<\/p>\n<\/div>\n<\/article>\n<\/section>\n\n<h2>Auditorias de seguran\u00e7a<\/h2>\n<p>A Auditoria Anual de Seguran\u00e7a da Adix \u00e9 uma inspec\u00e7\u00e3o abrangente de todos os componentes e sistemas cr\u00edticos de seguran\u00e7a. Uma Ex-ASA \u00e9 uma solu\u00e7\u00e3o que fornece um meio de conformidade com as Directivas ATEX se realizada anualmente. Um Ex-ASA tamb\u00e9m pode ser ben\u00e9fico ao comprar equipamento usado ou ap\u00f3s uma remodela\u00e7\u00e3o ou modifica\u00e7\u00e3o.<\/p>\n<p>A auditoria de seguran\u00e7a anual da Adix EX \u00e9 uma inspec\u00e7\u00e3o abrangente dos componentes cr\u00edticos de seguran\u00e7a nas nossas convers\u00f5es de protec\u00e7\u00e3o contra explos\u00f5es. O EX-ASA assegura que a integridade e seguran\u00e7a do seu equipamento de manuseamento de materiais n\u00e3o seja comprometida durante a sua vida \u00fatil. Ao lidar com materiais potencialmente perigosos, a menor fa\u00edsca ou aumento de temperatura pode tornar-se uma fonte de igni\u00e7\u00e3o, e \u00e9 imperativo que todo o equipamento Adix seja mantido ao mais alto n\u00edvel.<\/p>\n<p>A inspec\u00e7\u00e3o pode ser realizada em qualquer parte do mundo por um dos nossos engenheiros acreditados pelo IsmATEX. Todos os componentes cr\u00edticos de seguran\u00e7a do sistema de protec\u00e7\u00e3o contra explos\u00f5es Adix s\u00e3o inspeccionados e registados, incluindo inv\u00f3lucros, cabos e prensa-cabos Exd, dispositivos de desligamento, condutividade.<\/p>\n<p><strong>Porque \u00e9 que preciso de um EX-ASA?<\/strong><\/p>\n<p>A ATEX 1999\/92\/CE exige que o utilizador final &#8220;demonstre que o equipamento de trabalho \u00e9 concebido e mantido com o devido respeito pela seguran\u00e7a&#8221;. Todo o equipamento \u00e9 mantido em conformidade com a norma EN60079-17, que estabelece que deve ser introduzida uma rotina de inspec\u00e7\u00e3o para garantir a continua\u00e7\u00e3o do funcionamento seguro do equipamento.<\/p>\n<p>Se n\u00e3o tiverem sido encontradas irregularidades, o cami\u00e3o ser\u00e1 declarado seguro para utiliza\u00e7\u00e3o e ser\u00e1 emitido um certificado de apoio ao seu Documento de Protec\u00e7\u00e3o contra Explos\u00e3o (EPD). As irregularidades devem ser imediatamente reparadas pelo engenheiro de servi\u00e7o da Adix ou por um engenheiro formado pela Adix do seu fornecedor de servi\u00e7os. Uma vez reparado correctamente, o equipamento pode ser inspeccionado de novo e emitido um certificado.<\/p>\n<p>Recomendamos que seja realizado anualmente um EX-ASA para assegurar que o seu equipamento est\u00e1 totalmente protegido e a funcionar correctamente.<\/p>\n<section class=\"shortcode_articles two_columns\">\n<article>\n<figure><img decoding=\"async\" src=\"https:\/\/adixatex.com\/wp-content\/uploads\/2021\/02\/5.-suministro-de-piezas.jpg\" alt=\"Fornecimento de pe\u00e7as\"\/><\/figure>\n<div class=\"info\"><span class=\"tag\">Fornecimento de pe\u00e7as<\/span>\n<h3><a href=\"https:\/\/adixatex.com\/contacto\/\">Fornecimento de pe\u00e7as<\/a><\/h3>\n\n<p>Oferecemos uma vasta gama de pe\u00e7as sobressalentes para equipamento. As listas de pe\u00e7as s\u00e3o fornecidas com cada novo desempenho, fornecendo n\u00fameros de pe\u00e7as espec\u00edficos para que as pe\u00e7as possam ser encomendadas rapidamente.<\/p>\n<p>Se o n\u00famero da pe\u00e7a n\u00e3o estiver dispon\u00edvel, contactar a equipa de pe\u00e7as ou enviar um pedido com uma explica\u00e7\u00e3o completa do item e o n\u00famero de constru\u00e7\u00e3o Adix.<\/p>\n<p>Uma parte n\u00e3o autorizada pode comprometer a seguran\u00e7a do seu povo e dos seus neg\u00f3cios.<\/p>\n<p>Se tiver quaisquer perguntas sobre pe\u00e7as, certifica\u00e7\u00e3o e servi\u00e7o, n\u00e3o hesite em contactar-nos directamente.<\/p>\n<p><span class=\"link false_link\" data-link=\"parent_h3\">Mais informa\u00e7\u00f5es<i><svg fill=\"none\" height=\"8\" viewBox=\"0 0 21 8\" width=\"21\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m20.3536 4.35355c.1952-.19526.1952-.51184 0-.70711l-3.182-3.181975c-.1953-.195263-.5119-.195263-.7071 0-.1953.195262-.1953.511844 0 .707105l2.8284 2.82843-2.8284 2.82843c-.1953.19526-.1953.51184 0 .7071.1952.19526.5118.19526.7071 0zm-20.35359996.14645h19.99999996v-1h-20.00000004z\" fill=\"#000\"><\/path><\/svg><\/i><\/span><\/p><\/div>\n<\/article>\n<article>\n<figure><img decoding=\"async\" src=\"https:\/\/adixatex.com\/wp-content\/uploads\/2021\/02\/6.-entrenamiento-tecnicos.jpg\" alt=\"Forma\u00e7\u00e3o para t\u00e9cnicos de manuten\u00e7\u00e3o\"\/><\/figure>\n<div class=\"info\"><span class=\"tag\">T\u00e9cnicos de manuten\u00e7\u00e3o<\/span>\n<h3>Forma\u00e7\u00e3o para t\u00e9cnicos de manuten\u00e7\u00e3o<\/h3>\n\n<p>Qualquer sistema Adix necessitar\u00e1 de manuten\u00e7\u00e3o regular para assegurar o seu correcto funcionamento, mas mais importante ainda, para assegurar que o equipamento est\u00e1 sempre totalmente protegido. Oferecemos uma gama de cursos de forma\u00e7\u00e3o de engenheiros, dependendo da aplica\u00e7\u00e3o.<\/p>\n<p>Oferecemos uma gama de cursos de forma\u00e7\u00e3o concebidos para ajudar os engenheiros de manuten\u00e7\u00e3o e de obra, engenheiros de servi\u00e7o de campo e gestores de servi\u00e7o a manter o equipamento Adix no terreno.<\/p>\n<p>Conte\u00fado inclui: introdu\u00e7\u00e3o b\u00e1sica \u00e0 protec\u00e7\u00e3o contra explos\u00f5es, m\u00e9todos de protec\u00e7\u00e3o, manuten\u00e7\u00e3o e inspec\u00e7\u00e3o, Zona 1, 2, 21 e 22, equipamento mec\u00e2nico e el\u00e9ctrico. Ap\u00f3s uma avalia\u00e7\u00e3o satisfat\u00f3ria, s\u00e3o emitidos certificados e manuais t\u00e9cnicos completos.<\/p>\n<\/div>\n<\/article>\n<\/section>\n\n<h2 class=\"tag\">Reservar um Engenheiro de Servi\u00e7o ADIX<\/h2>\n<p>Os engenheiros da Adix est\u00e3o dispon\u00edveis para ajudar os clientes em qualquer parte do mundo.<\/p>\n<p>Os t\u00e9cnicos de campo podem ser enviados para prestar apoio no local para instala\u00e7\u00e3o, comissionamento ou resolu\u00e7\u00e3o de problemas e repara\u00e7\u00f5es no caso de algo correr mal com o seu equipamento. A nossa equipa tem as certifica\u00e7\u00f5es e forma\u00e7\u00e3o necess\u00e1rias para p\u00f4r o seu equipamento a funcionar o mais rapidamente poss\u00edvel.<\/p>\n<p>A nossa equipa de engenheiros \u00e9 uma segunda linha de apoio a distribuidores e redes OEM em qualquer parte do mundo. Os t\u00e9cnicos de campo da Adix est\u00e3o dispon\u00edveis para ajudar na resolu\u00e7\u00e3o de problemas e repara\u00e7\u00e3o de falhas complexas para ajudar a p\u00f4r o seu equipamento a funcionar em seguran\u00e7a o mais rapidamente poss\u00edvel.<\/p>\n<div class=\"shortcode_link\"><p><a href=\"https:\/\/adixatex.com\/contacto\/\">M\u00e1s informaci\u00f3n<i><svg fill=\"none\" height=\"8\" viewBox=\"0 0 21 8\" width=\"21\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m20.3536 4.35355c.1952-.19526.1952-.51184 0-.70711l-3.182-3.181975c-.1953-.195263-.5119-.195263-.7071 0-.1953.195262-.1953.511844 0 .707105l2.8284 2.82843-2.8284 2.82843c-.1953.19526-.1953.51184 0 .7071.1952.19526.5118.19526.7071 0zm-20.35359996.14645h19.99999996v-1h-20.00000004z\" fill=\"#000\"><\/path><\/svg><\/i><\/a><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auditorias de seguran\u00e7a A Auditoria Anual de Seguran\u00e7a da Adix \u00e9 uma inspec\u00e7\u00e3o abrangente de todos os componentes e sistemas cr\u00edticos de seguran\u00e7a. Uma Ex-ASA \u00e9 uma solu\u00e7\u00e3o que fornece um meio de conformidade com as Directivas ATEX se realizada anualmente. Um Ex-ASA tamb\u00e9m pode ser ben\u00e9fico ao comprar equipamento usado ou ap\u00f3s uma remodela\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2993,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/corporative.php","meta":{"footnotes":""},"class_list":["post-2870","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servi\u00e7os - Adixatex<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servi\u00e7os - Adixatex\" \/>\n<meta property=\"og:description\" content=\"Auditorias de seguran\u00e7a A Auditoria Anual de Seguran\u00e7a da Adix \u00e9 uma inspec\u00e7\u00e3o abrangente de todos os componentes e sistemas cr\u00edticos de seguran\u00e7a. Uma Ex-ASA \u00e9 uma solu\u00e7\u00e3o que fornece um meio de conformidade com as Directivas ATEX se realizada anualmente. Um Ex-ASA tamb\u00e9m pode ser ben\u00e9fico ao comprar equipamento usado ou ap\u00f3s uma remodela\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www2.adixatex.com\/servicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Adixatex\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T12:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@adixprotection\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/\",\"url\":\"https:\/\/www2.adixatex.com\/servicios\/\",\"name\":\"Servi\u00e7os - Adixatex\",\"isPartOf\":{\"@id\":\"https:\/\/www2.adixatex.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg\",\"datePublished\":\"2021-02-22T09:23:20+00:00\",\"dateModified\":\"2021-11-18T12:46:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www2.adixatex.com\/servicios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/#primaryimage\",\"url\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg\",\"contentUrl\":\"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www2.adixatex.com\/servicios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www2.adixatex.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi\u00e7os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www2.adixatex.com\/#website\",\"url\":\"https:\/\/www2.adixatex.com\/\",\"name\":\"Adixatex\",\"description\":\"Prevenci\u00f3n y protecci\u00f3n de atm\u00f3sferas explosivas\",\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servi\u00e7os - Adixatex","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"Servi\u00e7os - Adixatex","og_description":"Auditorias de seguran\u00e7a A Auditoria Anual de Seguran\u00e7a da Adix \u00e9 uma inspec\u00e7\u00e3o abrangente de todos os componentes e sistemas cr\u00edticos de seguran\u00e7a. Uma Ex-ASA \u00e9 uma solu\u00e7\u00e3o que fornece um meio de conformidade com as Directivas ATEX se realizada anualmente. Um Ex-ASA tamb\u00e9m pode ser ben\u00e9fico ao comprar equipamento usado ou ap\u00f3s uma remodela\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/www2.adixatex.com\/servicios\/","og_site_name":"Adixatex","article_modified_time":"2021-11-18T12:46:03+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@adixprotection","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www2.adixatex.com\/servicios\/","url":"https:\/\/www2.adixatex.com\/servicios\/","name":"Servi\u00e7os - Adixatex","isPartOf":{"@id":"https:\/\/www2.adixatex.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www2.adixatex.com\/servicios\/#primaryimage"},"image":{"@id":"https:\/\/www2.adixatex.com\/servicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg","datePublished":"2021-02-22T09:23:20+00:00","dateModified":"2021-11-18T12:46:03+00:00","breadcrumb":{"@id":"https:\/\/www2.adixatex.com\/servicios\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www2.adixatex.com\/servicios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www2.adixatex.com\/servicios\/#primaryimage","url":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg","contentUrl":"https:\/\/www2.adixatex.com\/wp-content\/uploads\/2021\/02\/1.-servicios.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www2.adixatex.com\/servicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www2.adixatex.com\/"},{"@type":"ListItem","position":2,"name":"Servi\u00e7os"}]},{"@type":"WebSite","@id":"https:\/\/www2.adixatex.com\/#website","url":"https:\/\/www2.adixatex.com\/","name":"Adixatex","description":"Prevenci\u00f3n y protecci\u00f3n de atm\u00f3sferas explosivas","inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/pages\/2870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=2870"}],"version-history":[{"count":9,"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/pages\/2870\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/pages\/2870\/revisions\/3281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/media\/2993"}],"wp:attachment":[{"href":"https:\/\/www2.adixatex.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=2870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}